{"id":6,"count":1,"description":"","link":"https:\/\/www.tobiascaldarella.de\/blog\/it\/category\/linux\/3g\/","name":"3G","slug":"3g","taxonomy":"category","parent":4,"meta":[],"_links":{"self":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/categories\/6"}],"collection":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/categories\/4"}],"wp:post_type":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}