{"id":45,"date":"2015-10-14T23:36:15","date_gmt":"2015-10-14T21:36:15","guid":{"rendered":"https:\/\/www.die-schrages.de\/tobias\/blog\/?p=45"},"modified":"2015-11-16T20:59:20","modified_gmt":"2015-11-16T19:59:20","slug":"t-mobile-lte-stick-huawei-e-398","status":"publish","type":"post","link":"https:\/\/www.tobiascaldarella.de\/blog\/it\/2015\/10\/14\/t-mobile-lte-stick-huawei-e-398\/","title":{"rendered":"Chiavetta LTE Huawei E398"},"content":{"rendered":"<p>Pure con Ubuntu 15.04 la mia chiavetta LTE Huawei E398 non veniva riconosciuta automaticamente. Durante l&#8217;ultima settimana ero stufo di avviare manualmente usb_modeswitch ogni volta che collegavo la chiavetta o il computer tornava dallo stand-by.<br \/>\nQuindi ho aggiunto una nuova udev-rule e uno script che automaticamente lancia usb_modeswitch diverse volte per garantire un riconoscimento affidabile della chiavetta.<\/p>\n<p>Ho pacchettato tutto in un .deb file, se hai lo stesso problema, probabilmente questo pacchetto lo pu\u00f2 risolvere!<\/p>\n<p><a href=\"http:\/\/www.die-schrages.de\/tobias\/files\/huawei-e398-0.1.deb\">Pacchetto Debian<\/a><br \/>\n<a href=\"https:\/\/www.die-schrages.de\/tobias\/wordpress\/wp-content\/uploads\/2015\/10\/IMG_20151015_1220511.jpg\"><img loading=\"lazy\" class=\"size-medium wp-image-56 aligncenter\" src=\"https:\/\/www.die-schrages.de\/tobias\/wordpress\/wp-content\/uploads\/2015\/10\/IMG_20151015_1220511-300x221.jpg\" alt=\"IMG_20151015_122051\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.tobiascaldarella.de\/wordpress\/wp-content\/uploads\/2015\/10\/IMG_20151015_1220511-300x221.jpg 300w, https:\/\/www.tobiascaldarella.de\/wordpress\/wp-content\/uploads\/2015\/10\/IMG_20151015_1220511.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>PS: <a href=\"http:\/\/www.die-schrages.de\/tobias\/files\/huawei-e398-0.1.sig\">la firma digitale per verificare il pacchetto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pure con Ubuntu 15.04 la mia chiavetta LTE Huawei E398 non veniva riconosciuta automaticamente. Durante l&#8217;ultima settimana ero stufo di avviare manualmente usb_modeswitch ogni volta che collegavo la chiavetta o <a class=\"more-link\" href=\"https:\/\/www.tobiascaldarella.de\/blog\/it\/2015\/10\/14\/t-mobile-lte-stick-huawei-e-398\/\">Continue Reading &amp;rarr;<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6,4,7,5],"tags":[10,11,8,12,9],"translation":{"provider":"WPGlobus","version":"2.7.11","language":"it","enabled_languages":["de","it","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"it":{"title":true,"content":true,"excerpt":false},"en":{"title":true,"content":true,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/posts\/45"}],"collection":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/comments?post=45"}],"version-history":[{"count":12,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/posts\/45\/revisions"}],"predecessor-version":[{"id":60,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/posts\/45\/revisions\/60"}],"wp:attachment":[{"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/media?parent=45"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/categories?post=45"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tobiascaldarella.de\/blog\/it\/wp-json\/wp\/v2\/tags?post=45"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}